{"id":73573,"date":"2026-04-08T19:05:09","date_gmt":"2026-04-08T23:05:09","guid":{"rendered":"https:\/\/cmaontario.ca\/?post_type=tribe_events&#038;p=73573"},"modified":"2026-05-04T17:59:22","modified_gmt":"2026-05-04T21:59:22","slug":"r2i-tuneup-conference","status":"publish","type":"tribe_events","link":"https:\/\/cmaontario.ca\/fr\/event\/r2i-tuneup-conference\/","title":{"rendered":"CONF\u00c9RENCE R2I TUNEUP"},"content":{"rendered":"<p>Lancez-vous sur la voie du succ\u00e8s dans l'industrie musicale gr\u00e2ce \u00e0 des conseils d'experts, des outils pratiques et des strat\u00e9gies \u00e9prouv\u00e9es. Cette conf\u00e9rence est con\u00e7ue pour vous doter des connaissances et des ressources n\u00e9cessaires afin de naviguer en toute confiance dans le monde effr\u00e9n\u00e9 de la musique et de jeter les bases d'une carri\u00e8re durable et prosp\u00e8re.<\/p>\n<p><b>Samedi<\/b><\/p>\n<ul>\n<li>9h30 \u2013 10h45 (75 minutes) \u2013 <strong>Licence de synchronisation<\/strong><\/li>\n<li>10h55 \u2013 12h25 (90 minutes) \u2013 <strong>Comprendre les redevances<\/strong><\/li>\n<li>12:30 \u2013 14:00 (90 minutes) \u2013 <strong>Assembl\u00e9e g\u00e9n\u00e9rale et r\u00e9union publique<\/strong><\/li>\n<li>14h10 \u2013 15h25 (75 minutes) \u2013 <strong>Masterclass de Composition de Chansons<\/strong><\/li>\n<\/ul>\n<hr \/>\n<p><b>9:30 \u2013 10:45<\/b><\/p>\n<p><b>Diffuser votre musique \u00e0 l'\u00e9cran : La licence de synchronisation (75 minutes)<\/b><\/p>\n<p>Vous \u00eates-vous d\u00e9j\u00e0 demand\u00e9 comment les chansons se retrouvent dans les \u00e9missions de t\u00e9l\u00e9vision, les films, les publicit\u00e9s et les jeux vid\u00e9o ? La licence de synchronisation est l'un des moyens les plus puissants de g\u00e9n\u00e9rer des revenus et d'atteindre de nouveaux publics \u2014 mais y percer demande plus que de la chance.<\/p>\n<p>Dans cette session interactive, des superviseurs musicaux, des agents de synchronisation et des artistes ayant connu un r\u00e9el succ\u00e8s en synchronisation partageront exactement ce qu'ils recherchent, comment pr\u00e9parer votre catalogue et comment proposer efficacement vos titres. Vous apprendrez comment rendre votre musique pr\u00eate pour la synchronisation, comprendre les termes cl\u00e9s des contrats et \u00e9viter les erreurs de d\u00e9butant qui peuvent vous co\u00fbter des opportunit\u00e9s.<\/p>\n<p>Que vous soyez novice en synchronisation ou que vous pitchiez d\u00e9j\u00e0, cette session vous donnera des connaissances d'initi\u00e9s et des strat\u00e9gies pratiques pour vous aider \u00e0 d\u00e9crocher des placements et \u00e0 faire entendre votre musique \u00e0 l'\u00e9cran.<\/p>\n<p>\u00c0 la fin de cette session, les participants seront capables de :<\/p>\n<ul>\n<li>\u00a0 \u00a0 \u00a0 Comprendre ce qu'est la licence de synchronisation et pourquoi elle est importante en tant que source de revenus.<\/li>\n<li>\u00a0 \u00a0 \u00a0 Les superviseurs musicaux et les agents de synchronisation recherchent plusieurs \u00e9l\u00e9ments lors de la s\u00e9lection de chansons.\n\n**1. L'humeur et l'\u00e9motion :** La chanson doit correspondre \u00e0 l'ambiance et \u00e0 l'\u00e9motion de la sc\u00e8ne ou du projet. Elle doit amplifier le sentiment que le r\u00e9alisateur ou le cr\u00e9ateur essaie de transmettre.\n\n**2. La narration et les paroles :** Les paroles peuvent souvent raconter une histoire ou exprimer un sentiment qui compl\u00e8te le r\u00e9cit visuel. Si les paroles sont pertinentes et r\u00e9sonnent avec l'action \u00e0 l'\u00e9cran, cela peut avoir un impact consid\u00e9rable.\n\n**3. Le tempo et le rythme :** Le rythme de la musique doit correspondre au rythme de la sc\u00e8ne. Une sc\u00e8ne d'action n\u00e9cessitera un tempo plus rapide, tandis qu'une sc\u00e8ne \u00e9mouvante ou introspective pourrait b\u00e9n\u00e9ficier d'un tempo plus lent.\n\n**4. Le caract\u00e8re unique et l'originalit\u00e9 :** Les superviseurs cherchent souvent des chansons qui se d\u00e9marquent, qui ne sont pas trop omnipr\u00e9sentes ou \u00e9cul\u00e9es. Une piste unique peut rendre un projet m\u00e9morable.\n\n**5. La qualit\u00e9 de la production :** La chanson doit \u00eatre bien produite, avec un son clair et professionnel. Une mauvaise qualit\u00e9 audio peut distraire et nuire \u00e0 l'exp\u00e9rience globale.\n\n**6. La disponibilit\u00e9 et les droits :** C'est un aspect crucial. La musique doit \u00eatre disponible pour l'octroi de licences, et les droits doivent \u00eatre clairement d\u00e9finis. Les superviseurs et agents doivent savoir qui d\u00e9tient les droits d'auteur et les droits d'enregistrement pour pouvoir n\u00e9gocier les licences.\n\n**7. Le potentiel commercial et l'attrait pour le public :** Bien que ce ne soit pas toujours le facteur principal, la musique qui a le potentiel d'\u00eatre populaire aupr\u00e8s du public cible peut \u00eatre un avantage. Elle peut aider \u00e0 attirer l'attention sur le projet.\n\n**8. La pertinence pour le genre et le public cible :** La musique doit correspondre au genre du projet (film, s\u00e9rie t\u00e9l\u00e9vis\u00e9e, publicit\u00e9, jeu vid\u00e9o) et plaire au public auquel le projet s'adresse.\n\n**9. La polyvalence :** Certaines chansons peuvent \u00eatre utilis\u00e9es de diff\u00e9rentes mani\u00e8res, que ce soit comme musique de fond, pour accentuer un moment cl\u00e9, ou m\u00eame comme \u00e9l\u00e9ment narratif principal.\n\n**10. La connaissance du catalogue :** Les superviseurs et agents ont souvent une connaissance approfondie des catalogues musicaux, y compris des artistes ind\u00e9pendants, pour trouver la perle rare qui correspond parfaitement aux besoins du projet.\n\nEn r\u00e9sum\u00e9, il s'agit d'un m\u00e9lange d'intuition artistique, de compr\u00e9hension narrative et de consid\u00e9rations pratiques li\u00e9es aux licences et aux droits.<\/li>\n<li>\u00a0 \u00a0 \u00a0 Pr\u00e9parer et organiser leur catalogue pour qu'il soit pr\u00eat \u00e0 \u00eatre synchronis\u00e9.<\/li>\n<li>\u00a0 \u00a0 \u00a0 Reconna\u00eetre les termes et pi\u00e8ges courants des contrats de synchronisation.<\/li>\n<li>\u00a0 \u00a0 \u00a0 Appliquez des strat\u00e9gies pratiques pour proposer de la musique efficacement.<\/li>\n<\/ul>\n<p><b>Public<\/b> Artistes, auteurs-compositeurs, producteurs et managers int\u00e9ress\u00e9s par la licence synchronis\u00e9e<br \/>\n<b>Animateur :<\/b> Tristen Coffey, Agent de synchronisation, The HOOK Sync Group<\/p>\n<p><b>Pan\u00e9listes :<\/b><\/p>\n<ul>\n<li>Cadence Grace, Artiste\/Paroli\u00e8re<\/li>\n<li>Joelle May, Directrice G\u00e9n\u00e9rale, New Motor Records<\/li>\n<\/ul>\n<hr \/>\n<p><b>10h55 \u2013 12h25<\/b><\/p>\n<p><b>Comprendre les redevances \u2014 Il y a de l'argent qui vous attend (90 minutes)\u00a0<\/b><br \/>\n<b>Pr\u00e9sent\u00e9 par ACTRA\/RACS<\/b><\/p>\n<p>Laissez-vous de l'argent sur la table ? En tant qu'artiste, auteur-compositeur ou interpr\u00e8te, les redevances sont l'une des sources de revenus les plus importantes \u2014 mais seulement si vous savez comment les r\u00e9clamer. Cet atelier interactif vous expliquera SOCAN, SoundExchange\/CMRRA, ARTISTI, SOPROQ, et plus encore, en vous montrant exactement comment enregistrer, collecter et suivre les redevances auxquelles vous avez droit.<\/p>\n<p>Gr\u00e2ce \u00e0 des exemples concrets, des activit\u00e9s pratiques et des outils professionnels, vous apprendrez \u00e0 d\u00e9couvrir des revenus cach\u00e9s, \u00e0 organiser vos flux de redevances et \u00e0 vous assurer d'\u00eatre pay\u00e9 pour votre travail. Vous repartirez avec un plan d'action clair, une liste de contr\u00f4le pour le suivi des redevances et la confiance n\u00e9cessaire pour g\u00e9rer vos gains comme un professionnel.<\/p>\n<p>\u00c0 la fin de cet atelier, les participants seront capables de :<\/p>\n<ul>\n<li>Identifier les diff\u00e9rents types de redevances disponibles pour les artistes, les auteurs-compositeurs et les interpr\u00e8tes.<\/li>\n<li>Comprendre comment s'inscrire aupr\u00e8s des soci\u00e9t\u00e9s de gestion collective (SOCAN, SoundExchange, ARTISTI, SOPROQ, etc.). Note : ACTRA\/RACS per\u00e7oit aupr\u00e8s de SoundExchange<\/li>\n<li>\u00a0Cartographier leurs propres flux de revenus de redevances.<\/li>\n<li>Appliquer des outils pratiques pour suivre les revenus et s'assurer de ne pas laisser d'argent sur la table.<\/li>\n<\/ul>\n<p><b>Public<\/b> Artistes, auteurs-compositeurs, interpr\u00e8tes et professionnels de l'industrie musicale<\/p>\n<p><b>Animateur :<\/b><\/p>\n<ul>\n<li>Andrew Karis, Directeur adjoint, ACTRA PRS<\/li>\n<\/ul>\n<p><strong>Pan\u00e9listes :<\/strong><\/p>\n<ul>\n<li>Marianne Anderson, Responsable des relations \u00e9diteurs, CMRRA<\/li>\n<li>Michael Greaves, Directeur, Traitement des redevances et suivi des revenus, Anthem<\/li>\n<li>S\u00e9bastien Charest, Gestion de droits<\/li>\n<\/ul>\n<hr \/>\n<p><b>12h30 \u2013 14h00<\/b><\/p>\n<p><b>Assembl\u00e9e g\u00e9n\u00e9rale annuelle et Forum aux questions (90 minutes)<\/b><\/p>\n<p>Rejoignez-nous pour l'assembl\u00e9e g\u00e9n\u00e9rale annuelle et la table ronde 2026 de la CMAOntario \u2014 votre occasion de contribuer \u00e0 fa\u00e7onner l'avenir de l'association. Cette session offre aux membres une plateforme pour partager des id\u00e9es, des perspectives et des priorit\u00e9s, garantissant ainsi que l'association comprenne et refl\u00e8te les besoins de sa communaut\u00e9.<\/p>\n<p>En participant aux discussions et en apportant leurs contributions, les membres jouent un r\u00f4le direct dans l\u2019\u00e9laboration des plans strat\u00e9giques, la d\u00e9finition des priorit\u00e9s et l\u2019influence des initiatives qui correspondent \u00e0 la vision et aux objectifs communs de CMAOntario. Venez contribuer, vous connecter et aider \u00e0 tracer la voie \u00e0 suivre pour la communaut\u00e9 de la musique country de l\u2019Ontario.<\/p>\n<ul>\n<li>Patrick Duffy, Pr\u00e9sident de la CMAOntario<\/li>\n<li>Brian Allen, Secr\u00e9taire CMAOntario<\/li>\n<li>Brooke Dunford, Tr\u00e9sori\u00e8re de la CMAOntario<\/li>\n<\/ul>\n<hr \/>\n<p><b>14h10 \u2013 15h25<\/b><\/p>\n<p><b>Masterclass de composition \u2013 Perspectives et collaboration (75 minutes)\u00a0<\/b><\/p>\n<p>\u00c0 quoi ressemble la cr\u00e9ation d'une chanson par des paroliers professionnels pour un artiste \u00e9mergent ? Cette masterclass r\u00e9v\u00e8le les coulisses de la salle d'\u00e9criture collaborative moderne \u2013 en direct, sans script et en temps r\u00e9el.<\/p>\n<p>Le producteur et auteur-compositeur chevronn\u00e9 Douglas Romanow (Don Amero, Rebecca Rain, Jade Hilton, Nicole Rayy) r\u00e9unit la paroli\u00e8re de Nashville Chrystal Grainger et l'artiste country-pop montante Parker Graye pour un atelier interactif et une d\u00e9monstration de co-\u00e9criture en direct.<\/p>\n<p>La session est con\u00e7ue pour offrir aux participants trois choses en un apr\u00e8s-midi : de nouveaux outils cr\u00e9atifs et de l'inspiration des artistes eux-m\u00eames, un si\u00e8ge au premier rang pour une session d'\u00e9criture professionnelle qui se d\u00e9roule dans la salle, et des connaissances pratiques de l'industrie pour construire une carri\u00e8re durable autour de leur art.<\/p>\n<p>\u00c0 la fin de la session, les participants repartiront avec :<\/p>\n<ul>\n<li>Une r\u00e9elle compr\u00e9hension de la fa\u00e7on dont les sessions de co-\u00e9criture professionnelles sont structur\u00e9es et g\u00e9r\u00e9es<\/li>\n<li>Outils pratiques pour la g\u00e9n\u00e9ration d'id\u00e9es, l'\u00e9criture de paroles, la m\u00e9lodie, les refrains et le d\u00e9passement du blocage de l'\u00e9crivain<\/li>\n<li>Un aper\u00e7u direct du mod\u00e8le topliner\/track qui pilote une grande partie de l'industrie actuelle<\/li>\n<li>Une feuille de route plus claire pour b\u00e2tir et faire progresser une carri\u00e8re professionnelle d'auteur-compositeur ou d'artiste<\/li>\n<li>Inspiration fra\u00eeche \u2014 et un concept de chanson qui a \u00e9t\u00e9 commenc\u00e9 en direct dans la pi\u00e8ce<\/li>\n<\/ul>\n<p>Voici la salle d'\u00e9criture \u2014 sans filtre.<\/p>\n<p><strong>Public<\/strong>Artistes, auteurs-compositeurs, producteurs<br \/>\n<strong>Animateur<\/strong>Douglas Romanow, Producteur de musique \/ Auteur-compositeur \/ Mixeur Dolby Atmos chez dR Music<\/p>\n<p><strong>Avec<\/strong>:<\/p>\n<ul>\n<li>OUDi (Chrystal Grainger), Artiste\/Auteur-compositeur<\/li>\n<li>Parker Graye, Artiste\/Auteur-compositeur<\/li>\n<\/ul>\n<hr \/>\n<p><b><a href=\"https:\/\/www.visitmississauga.ca\/\">Visitez Mississauga<\/a> |\u00a0 <a href=\"https:\/\/www.portcredit.com\/\">Port Credit BIA<\/a><\/b><\/p>\n<p><b>Rendu possible avec le soutien d'Ontario Cr\u00e9atif<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-53706 alignleft\" src=\"https:\/\/cmaontario.ca\/wp-content\/uploads\/2024\/04\/ontario-creates-logo.jpg\" alt=\"Ontario Creates logo\" width=\"300\" height=\"82\" srcset=\"https:\/\/cmaontario.ca\/wp-content\/uploads\/2024\/04\/ontario-creates-logo.jpg 300w, https:\/\/cmaontario.ca\/wp-content\/uploads\/2024\/04\/ontario-creates-logo-150x41.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Kickstart your path to success in the music industry with expert insights, practical tools, and proven strategies. This conference is designed to equip you with the knowledge and resources to&hellip;<\/p>","protected":false},"author":3,"featured_media":73819,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[],"class_list":["post-73573","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R2I TUNEUP CONFERENCE - Country Music Association of Ontario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cmaontario.ca\/fr\/event\/r2i-tuneup-conference\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R2I TUNEUP CONFERENCE - Country Music Association of Ontario\" \/>\n<meta property=\"og:description\" content=\"Kickstart your path to success in the music industry with expert insights, practical tools, and proven strategies. This conference is designed to equip you with the knowledge and resources to&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cmaontario.ca\/fr\/event\/r2i-tuneup-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"Country Music Association of Ontario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thecmaontario\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T21:59:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cmaontario.ca\/wp-content\/uploads\/2026\/04\/cmaontario26-square-copy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@theCMAOntario\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/\",\"url\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/\",\"name\":\"R2I TUNEUP CONFERENCE - Country Music Association of Ontario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cmaontario.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cmaontario26-square-copy.png\",\"datePublished\":\"2026-04-08T23:05:09+00:00\",\"dateModified\":\"2026-05-04T21:59:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cmaontario.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cmaontario26-square-copy.png\",\"contentUrl\":\"https:\\\/\\\/cmaontario.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cmaontario26-square-copy.png\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/event\\\/r2i-tuneup-conference\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cmaontario.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/cmaontario.ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R2I TUNEUP CONFERENCE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/#website\",\"url\":\"https:\\\/\\\/cmaontario.ca\\\/\",\"name\":\"Country Music Association of Ontario\",\"description\":\"Making Ontario Country Music Matter.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cmaontario.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/#organization\",\"name\":\"Country Music Association of Ontario\",\"url\":\"https:\\\/\\\/cmaontario.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cmaontario.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CMAO-Logo-vertical-MaroonBlu.png\",\"contentUrl\":\"https:\\\/\\\/cmaontario.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CMAO-Logo-vertical-MaroonBlu.png\",\"width\":512,\"height\":512,\"caption\":\"Country Music Association of Ontario\"},\"image\":{\"@id\":\"https:\\\/\\\/cmaontario.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thecmaontario\\\/\",\"https:\\\/\\\/x.com\\\/theCMAOntario\",\"https:\\\/\\\/www.instagram.com\\\/thecmaontario\\\/\",\"https:\\\/\\\/open.spotify.com\\\/user\\\/cmaontario\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R2I TUNEUP CONFERENCE - Country Music Association of Ontario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cmaontario.ca\/fr\/event\/r2i-tuneup-conference\/","og_locale":"fr_CA","og_type":"article","og_title":"R2I TUNEUP CONFERENCE - Country Music Association of Ontario","og_description":"Kickstart your path to success in the music industry with expert insights, practical tools, and proven strategies. This conference is designed to equip you with the knowledge and resources to&hellip;","og_url":"https:\/\/cmaontario.ca\/fr\/event\/r2i-tuneup-conference\/","og_site_name":"Country Music Association of Ontario","article_publisher":"https:\/\/www.facebook.com\/thecmaontario\/","article_modified_time":"2026-05-04T21:59:22+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/cmaontario.ca\/wp-content\/uploads\/2026\/04\/cmaontario26-square-copy.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@theCMAOntario","twitter_misc":{"Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/","url":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/","name":"R2I TUNEUP CONFERENCE - Country Music Association of Ontario","isPartOf":{"@id":"https:\/\/cmaontario.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/#primaryimage"},"image":{"@id":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/#primaryimage"},"thumbnailUrl":"https:\/\/cmaontario.ca\/wp-content\/uploads\/2026\/04\/cmaontario26-square-copy.png","datePublished":"2026-04-08T23:05:09+00:00","dateModified":"2026-05-04T21:59:22+00:00","breadcrumb":{"@id":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/#primaryimage","url":"https:\/\/cmaontario.ca\/wp-content\/uploads\/2026\/04\/cmaontario26-square-copy.png","contentUrl":"https:\/\/cmaontario.ca\/wp-content\/uploads\/2026\/04\/cmaontario26-square-copy.png","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/cmaontario.ca\/event\/r2i-tuneup-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cmaontario.ca\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/cmaontario.ca\/events\/"},{"@type":"ListItem","position":3,"name":"R2I TUNEUP CONFERENCE"}]},{"@type":"WebSite","@id":"https:\/\/cmaontario.ca\/#website","url":"https:\/\/cmaontario.ca\/","name":"Association de musique country de l'Ontario","description":"Faire conna\u00eetre la musique country de l'Ontario.","publisher":{"@id":"https:\/\/cmaontario.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cmaontario.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cmaontario.ca\/#organization","name":"Association de musique country de l'Ontario","url":"https:\/\/cmaontario.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cmaontario.ca\/#\/schema\/logo\/image\/","url":"https:\/\/cmaontario.ca\/wp-content\/uploads\/2025\/12\/CMAO-Logo-vertical-MaroonBlu.png","contentUrl":"https:\/\/cmaontario.ca\/wp-content\/uploads\/2025\/12\/CMAO-Logo-vertical-MaroonBlu.png","width":512,"height":512,"caption":"Country Music Association of Ontario"},"image":{"@id":"https:\/\/cmaontario.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thecmaontario\/","https:\/\/x.com\/theCMAOntario","https:\/\/www.instagram.com\/thecmaontario\/","https:\/\/open.spotify.com\/user\/cmaontario"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/73573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":11,"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/73573\/revisions"}],"predecessor-version":[{"id":73831,"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/73573\/revisions\/73831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/media\/73819"}],"wp:attachment":[{"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/media?parent=73573"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/tags?post=73573"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/cmaontario.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=73573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}